{"id":140,"date":"2009-06-27T21:12:13","date_gmt":"2009-06-27T21:12:13","guid":{"rendered":"http:\/\/alphaares.com.mialias.net\/2009\/06\/27\/gran-jornada-en-granollers\/"},"modified":"2015-11-02T12:18:09","modified_gmt":"2015-11-02T11:18:09","slug":"gran-jornada-en-granollers","status":"publish","type":"post","link":"https:\/\/www.alphaares.com\/es\/2009\/06\/27\/gran-jornada-en-granollers\/","title":{"rendered":"Gran jornada en Granollers"},"content":{"rendered":"<p align=\"justify\">Tal como prometimos hace una semanas, finalmente asistimos a la amable invitaci&oacute;n de la jornada Jugar x Jugar en Granollers. Fu&eacute; fant&aacute;stico. De los m&aacute;s de 3000 metros cuadrados dedicados a la feria general, nos reservaron una carpa muy grande para los clubes y entidades l&uacute;dicos invitados. <\/p>\n<p>&nbsp;<\/p>\n<div style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/alphaares.com\/mostra2\/main.php?g2_view=core.DownloadItem&#038;g2_itemId=284&#038;g2_serialNumber=1\" alt=\"Vista general de la Fira de Granollers\" title=\"Vista general de la Fira de Granollers\" width=\"201\" height=\"151\" \/><\/div>\n<p>&nbsp;<\/p>\n<p align=\"justify\">Estuvimos todo el d&iacute;a dejando el pabell&oacute;n de Alpha bien alto. Lo cierto es qe la organizaci&oacute;n se bolc&oacute; en recursos y disponibilidad. Una de las primeras sorpresas fu&eacute; el regalo de este t&oacute;tem informativo tan espectacular como inesperado.<\/p>\n<p>&nbsp;<\/p>\n<div style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/alphaares.com\/mostra2\/main.php?g2_view=core.DownloadItem&#038;g2_itemId=286&#038;g2_serialNumber=1\" alt=\"T&oacute;tem informatiu\" title=\"T&oacute;tem informatiu\" width=\"176\" height=\"235\" \/><\/div>\n<p>&nbsp;<\/p>\n<p>Sencillamente un placer. Nos invitaron a comer y nos dejaron escoger las mesas de juego. Todo esto y mucho m&aacute;s explicado con todo detalle <a href=\"http:\/\/landmeister.blogspot.com\/2009\/05\/abandono-dbmm-primera-parte.html\" target=\"_blank\">en mi blog personal<\/a> . En definitiva, una jornada inolvidable. El a&ntilde;o que viene hay que repetir. <img decoding=\"async\" src=\"mambots\/editors\/tinymce\/jscripts\/tiny_mce\/plugins\/emotions\/images\/smiley-laughing.gif\" border=\"0\" alt=\"Laughing\" title=\"Laughing\" \/><\/p>\n<p><!--more--><\/p>\n","protected":false},"excerpt":{"rendered":"<p align=\"justify\">Tal como prometimos hace una semanas, finalmente asistimos a la amable invitaci&oacute;n de la jornada Jugar x Jugar en Granollers. Fu&eacute; fant&aacute;stico. De los m&aacute;s de 3000 metros cuadrados dedicados a la feria general, nos reservaron una carpa muy grande para los clubes y entidades l&uacute;dicos invitados. <\/p>\n<p>&nbsp;<\/p>\n<div style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/alphaares.com\/mostra2\/main.php?g2_view=core.DownloadItem&#038;g2_itemId=284&#038;g2_serialNumber=1\" alt=\"Vista general de la Fira de Granollers\" title=\"Vista general de la Fira de Granollers\" width=\"201\" height=\"151\" \/><\/div>\n<p>&nbsp;<\/p>\n<p align=\"justify\">Estuvimos todo el d&iacute;a dejando el pabell&oacute;n de Alpha bien alto. Lo cierto es qe la organizaci&oacute;n se bolc&oacute; en recursos y disponibilidad. Una de las primeras sorpresas fu&eacute; el regalo de este t&oacute;tem informativo tan espectacular como inesperado.<\/p>\n<p>&nbsp;<\/p>\n<div style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/alphaares.com\/mostra2\/main.php?g2_view=core.DownloadItem&#038;g2_itemId=286&#038;g2_serialNumber=1\" alt=\"T&oacute;tem informatiu\" title=\"T&oacute;tem informatiu\" width=\"176\" height=\"235\" \/><\/div>\n<p>&nbsp;<\/p>\n<p>Sencillamente un placer. Nos invitaron a comer y nos dejaron escoger las mesas de juego. Todo esto y mucho m&aacute;s explicado con todo detalle <a href=\"http:\/\/landmeister.blogspot.com\/2009\/05\/abandono-dbmm-primera-parte.html\" target=\"_blank\">en mi blog personal<\/a> . En definitiva, una jornada inolvidable. El a&ntilde;o que viene hay que repetir. <img decoding=\"async\" src=\"mambots\/editors\/tinymce\/jscripts\/tiny_mce\/plugins\/emotions\/images\/smiley-laughing.gif\" border=\"0\" alt=\"Laughing\" title=\"Laughing\" \/><\/p>\n","protected":false},"author":3,"featured_media":410,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[16,15],"tags":[],"class_list":["post-140","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dbmm","category-figures"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gran jornada en Granollers - Alpha Ares<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.alphaares.com\/es\/2009\/06\/27\/gran-jornada-en-granollers\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gran jornada en Granollers - Alpha Ares\" \/>\n<meta property=\"og:description\" content=\"Tal como prometimos hace una semanas, finalmente asistimos a la amable invitaci&oacute;n de la jornada Jugar x Jugar en Granollers. Fu&eacute; fant&aacute;stico. De los m&aacute;s de 3000 metros cuadrados dedicados a la feria general, nos reservaron una carpa muy grande para los clubes y entidades l&uacute;dicos invitados. &nbsp;&nbsp;Estuvimos todo el d&iacute;a dejando el pabell&oacute;n de Alpha bien alto. Lo cierto es qe la organizaci&oacute;n se bolc&oacute; en recursos y disponibilidad. Una de las primeras sorpresas fu&eacute; el regalo de este t&oacute;tem informativo tan espectacular como inesperado.&nbsp;&nbsp;Sencillamente un placer. Nos invitaron a comer y nos dejaron escoger las mesas de juego. Todo esto y mucho m&aacute;s explicado con todo detalle en mi blog personal . En definitiva, una jornada inolvidable. El a&ntilde;o que viene hay que repetir.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.alphaares.com\/es\/2009\/06\/27\/gran-jornada-en-granollers\/\" \/>\n<meta property=\"og:site_name\" content=\"Alpha Ares\" \/>\n<meta property=\"article:published_time\" content=\"2009-06-27T21:12:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-11-02T11:18:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.alphaares.com\/wp-content\/uploads\/2015\/07\/main3.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"presidentalpha\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"presidentalpha\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.alphaares.com\\\/es\\\/2009\\\/06\\\/27\\\/gran-jornada-en-granollers\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alphaares.com\\\/es\\\/2009\\\/06\\\/27\\\/gran-jornada-en-granollers\\\/\"},\"author\":{\"name\":\"presidentalpha\",\"@id\":\"https:\\\/\\\/www.alphaares.com\\\/es\\\/#\\\/schema\\\/person\\\/14c876c0fed0367d87e27645b24f757b\"},\"headline\":\"Gran jornada en Granollers\",\"datePublished\":\"2009-06-27T21:12:13+00:00\",\"dateModified\":\"2015-11-02T11:18:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.alphaares.com\\\/es\\\/2009\\\/06\\\/27\\\/gran-jornada-en-granollers\\\/\"},\"wordCount\":156,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.alphaares.com\\\/es\\\/2009\\\/06\\\/27\\\/gran-jornada-en-granollers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.alphaares.com\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/main3.jpeg\",\"articleSection\":[\"DBMM\",\"Figures\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.alphaares.com\\\/es\\\/2009\\\/06\\\/27\\\/gran-jornada-en-granollers\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.alphaares.com\\\/es\\\/2009\\\/06\\\/27\\\/gran-jornada-en-granollers\\\/\",\"url\":\"https:\\\/\\\/www.alphaares.com\\\/es\\\/2009\\\/06\\\/27\\\/gran-jornada-en-granollers\\\/\",\"name\":\"Gran jornada en Granollers - Alpha Ares\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alphaares.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.alphaares.com\\\/es\\\/2009\\\/06\\\/27\\\/gran-jornada-en-granollers\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alphaares.com\\\/es\\\/2009\\\/06\\\/27\\\/gran-jornada-en-granollers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.alphaares.com\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/main3.jpeg\",\"datePublished\":\"2009-06-27T21:12:13+00:00\",\"dateModified\":\"2015-11-02T11:18:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.alphaares.com\\\/es\\\/#\\\/schema\\\/person\\\/14c876c0fed0367d87e27645b24f757b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.alphaares.com\\\/es\\\/2009\\\/06\\\/27\\\/gran-jornada-en-granollers\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.alphaares.com\\\/es\\\/2009\\\/06\\\/27\\\/gran-jornada-en-granollers\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.alphaares.com\\\/es\\\/2009\\\/06\\\/27\\\/gran-jornada-en-granollers\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.alphaares.com\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/main3.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.alphaares.com\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/main3.jpeg\",\"width\":640,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.alphaares.com\\\/es\\\/2009\\\/06\\\/27\\\/gran-jornada-en-granollers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.alphaares.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gran jornada en Granollers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.alphaares.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.alphaares.com\\\/es\\\/\",\"name\":\"Alpha Ares\",\"description\":\"\u00a0\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.alphaares.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.alphaares.com\\\/es\\\/#\\\/schema\\\/person\\\/14c876c0fed0367d87e27645b24f757b\",\"name\":\"presidentalpha\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1348ffc716a66b53266d7f53e0f7d245fbfd1d718327b1deb651f5f4b0d406ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1348ffc716a66b53266d7f53e0f7d245fbfd1d718327b1deb651f5f4b0d406ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1348ffc716a66b53266d7f53e0f7d245fbfd1d718327b1deb651f5f4b0d406ce?s=96&d=mm&r=g\",\"caption\":\"presidentalpha\"},\"url\":\"https:\\\/\\\/www.alphaares.com\\\/es\\\/author\\\/presidentalpha\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gran jornada en Granollers - Alpha Ares","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.alphaares.com\/es\/2009\/06\/27\/gran-jornada-en-granollers\/","og_locale":"es_ES","og_type":"article","og_title":"Gran jornada en Granollers - Alpha Ares","og_description":"Tal como prometimos hace una semanas, finalmente asistimos a la amable invitaci&oacute;n de la jornada Jugar x Jugar en Granollers. Fu&eacute; fant&aacute;stico. De los m&aacute;s de 3000 metros cuadrados dedicados a la feria general, nos reservaron una carpa muy grande para los clubes y entidades l&uacute;dicos invitados. &nbsp;&nbsp;Estuvimos todo el d&iacute;a dejando el pabell&oacute;n de Alpha bien alto. Lo cierto es qe la organizaci&oacute;n se bolc&oacute; en recursos y disponibilidad. Una de las primeras sorpresas fu&eacute; el regalo de este t&oacute;tem informativo tan espectacular como inesperado.&nbsp;&nbsp;Sencillamente un placer. Nos invitaron a comer y nos dejaron escoger las mesas de juego. Todo esto y mucho m&aacute;s explicado con todo detalle en mi blog personal . En definitiva, una jornada inolvidable. El a&ntilde;o que viene hay que repetir.","og_url":"https:\/\/www.alphaares.com\/es\/2009\/06\/27\/gran-jornada-en-granollers\/","og_site_name":"Alpha Ares","article_published_time":"2009-06-27T21:12:13+00:00","article_modified_time":"2015-11-02T11:18:09+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/www.alphaares.com\/wp-content\/uploads\/2015\/07\/main3.jpeg","type":"image\/jpeg"}],"author":"presidentalpha","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"presidentalpha","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.alphaares.com\/es\/2009\/06\/27\/gran-jornada-en-granollers\/#article","isPartOf":{"@id":"https:\/\/www.alphaares.com\/es\/2009\/06\/27\/gran-jornada-en-granollers\/"},"author":{"name":"presidentalpha","@id":"https:\/\/www.alphaares.com\/es\/#\/schema\/person\/14c876c0fed0367d87e27645b24f757b"},"headline":"Gran jornada en Granollers","datePublished":"2009-06-27T21:12:13+00:00","dateModified":"2015-11-02T11:18:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.alphaares.com\/es\/2009\/06\/27\/gran-jornada-en-granollers\/"},"wordCount":156,"commentCount":0,"image":{"@id":"https:\/\/www.alphaares.com\/es\/2009\/06\/27\/gran-jornada-en-granollers\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alphaares.com\/wp-content\/uploads\/2015\/07\/main3.jpeg","articleSection":["DBMM","Figures"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.alphaares.com\/es\/2009\/06\/27\/gran-jornada-en-granollers\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.alphaares.com\/es\/2009\/06\/27\/gran-jornada-en-granollers\/","url":"https:\/\/www.alphaares.com\/es\/2009\/06\/27\/gran-jornada-en-granollers\/","name":"Gran jornada en Granollers - Alpha Ares","isPartOf":{"@id":"https:\/\/www.alphaares.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.alphaares.com\/es\/2009\/06\/27\/gran-jornada-en-granollers\/#primaryimage"},"image":{"@id":"https:\/\/www.alphaares.com\/es\/2009\/06\/27\/gran-jornada-en-granollers\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alphaares.com\/wp-content\/uploads\/2015\/07\/main3.jpeg","datePublished":"2009-06-27T21:12:13+00:00","dateModified":"2015-11-02T11:18:09+00:00","author":{"@id":"https:\/\/www.alphaares.com\/es\/#\/schema\/person\/14c876c0fed0367d87e27645b24f757b"},"breadcrumb":{"@id":"https:\/\/www.alphaares.com\/es\/2009\/06\/27\/gran-jornada-en-granollers\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.alphaares.com\/es\/2009\/06\/27\/gran-jornada-en-granollers\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.alphaares.com\/es\/2009\/06\/27\/gran-jornada-en-granollers\/#primaryimage","url":"https:\/\/www.alphaares.com\/wp-content\/uploads\/2015\/07\/main3.jpeg","contentUrl":"https:\/\/www.alphaares.com\/wp-content\/uploads\/2015\/07\/main3.jpeg","width":640,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/www.alphaares.com\/es\/2009\/06\/27\/gran-jornada-en-granollers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.alphaares.com\/"},{"@type":"ListItem","position":2,"name":"Gran jornada en Granollers"}]},{"@type":"WebSite","@id":"https:\/\/www.alphaares.com\/es\/#website","url":"https:\/\/www.alphaares.com\/es\/","name":"Alpha Ares","description":"\u00a0","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.alphaares.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.alphaares.com\/es\/#\/schema\/person\/14c876c0fed0367d87e27645b24f757b","name":"presidentalpha","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1348ffc716a66b53266d7f53e0f7d245fbfd1d718327b1deb651f5f4b0d406ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1348ffc716a66b53266d7f53e0f7d245fbfd1d718327b1deb651f5f4b0d406ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1348ffc716a66b53266d7f53e0f7d245fbfd1d718327b1deb651f5f4b0d406ce?s=96&d=mm&r=g","caption":"presidentalpha"},"url":"https:\/\/www.alphaares.com\/es\/author\/presidentalpha\/"}]}},"_links":{"self":[{"href":"https:\/\/www.alphaares.com\/es\/wp-json\/wp\/v2\/posts\/140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alphaares.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alphaares.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alphaares.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alphaares.com\/es\/wp-json\/wp\/v2\/comments?post=140"}],"version-history":[{"count":1,"href":"https:\/\/www.alphaares.com\/es\/wp-json\/wp\/v2\/posts\/140\/revisions"}],"predecessor-version":[{"id":409,"href":"https:\/\/www.alphaares.com\/es\/wp-json\/wp\/v2\/posts\/140\/revisions\/409"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.alphaares.com\/es\/wp-json\/wp\/v2\/media\/410"}],"wp:attachment":[{"href":"https:\/\/www.alphaares.com\/es\/wp-json\/wp\/v2\/media?parent=140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alphaares.com\/es\/wp-json\/wp\/v2\/categories?post=140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alphaares.com\/es\/wp-json\/wp\/v2\/tags?post=140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}